{"id":247,"date":"2026-03-19T17:00:12","date_gmt":"2026-03-19T17:00:12","guid":{"rendered":"https:\/\/lendle.ee\/?page_id=247"},"modified":"2026-07-15T07:18:46","modified_gmt":"2026-07-15T07:18:46","slug":"lendle-maja-tutvustus","status":"publish","type":"page","link":"https:\/\/lendle.ee\/en\/lendle-maja-tutvustus\/","title":{"rendered":"Majutuse \u00dclevaade"},"content":{"rendered":"<div class=\"wp-block-group alignfull is-style-ext-preset--group--natural-1--section has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained is-style-ext-preset--group--natural-1--section--1\" style=\"border-style:none;border-width:0px;background-color:#ffffff;margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-cb-carousel-v2 alignwide cb-carousel-block\" data-cb-slides-per-view=\"1\" data-cb-slides-per-group=\"1\" data-cb-space-between=\"15\" data-cb-speed=\"300\" data-cb-navigation=\"true\" data-cb-pagination=\"true\" data-cb-autoplay=\"true\" data-cb-autoplay-speed=\"3000\" data-cb-breakpoints=\"{&quot;768&quot;:{&quot;slidesPerView&quot;:2,&quot;slidesPerGroup&quot;:1}}\"><div class=\"swiper\"><div class=\"cb-wrapper swiper-wrapper\">\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" data-id=\"719\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-1-1024x671.png\" alt=\"\" class=\"wp-image-719\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-1-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-1-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-1-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-1-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-1-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-1.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-2-1024x671.png\" alt=\"\" class=\"wp-image-721\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-2-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-2-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-2-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-2-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-2-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-2.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-3-1024x671.png\" alt=\"\" class=\"wp-image-722\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-3-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-3-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-3-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-3-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-3-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-3.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/Nimetu-kujundus-37-1-1024x671.png\" alt=\"\" class=\"wp-image-724\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/Nimetu-kujundus-37-1-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/Nimetu-kujundus-37-1-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/Nimetu-kujundus-37-1-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/Nimetu-kujundus-37-1-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/Nimetu-kujundus-37-1-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/Nimetu-kujundus-37-1.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" data-id=\"725\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-4-1-1024x671.png\" alt=\"\" class=\"wp-image-725\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-4-1-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-4-1-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-4-1-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-4-1-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-4-1-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAJA-4-1.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ESIK-1-1024x671.png\" alt=\"\" class=\"wp-image-727\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ESIK-1-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ESIK-1-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ESIK-1-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ESIK-1-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ESIK-1-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ESIK-1.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" data-id=\"729\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-1-1024x671.png\" alt=\"\" class=\"wp-image-729\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-1-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-1-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-1-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-1-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-1-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-1.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-2-1024x671.png\" alt=\"\" class=\"wp-image-785\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-2-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-2-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-2-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-2-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-2-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-2.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-2-1024x671.png\" alt=\"\" class=\"wp-image-730\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-2-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-2-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-2-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-2-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-2-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-2.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-3-1024x671.png\" alt=\"\" class=\"wp-image-731\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-3-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-3-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-3-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-3-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-3-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-3.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-4-1024x671.png\" alt=\"\" class=\"wp-image-732\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-4-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-4-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-4-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-4-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-4-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-4.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-2-1024x671.png\" alt=\"\" class=\"wp-image-786\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-2-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-2-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-2-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-2-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-2-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-2.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-6-1024x671.png\" alt=\"\" class=\"wp-image-734\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-6-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-6-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-6-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-6-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-6-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-6.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-7-1024x671.png\" alt=\"\" class=\"wp-image-735\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-7-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-7-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-7-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-7-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-7-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-7.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-8-1024x671.png\" alt=\"\" class=\"wp-image-736\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-8-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-8-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-8-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-8-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-8-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-8.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-9-1024x671.png\" alt=\"\" class=\"wp-image-737\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-9-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-9-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-9-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-9-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-9-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/ELUTUBA-9.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUB-1-1024x671.png\" alt=\"\" class=\"wp-image-740\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUB-1-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUB-1-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUB-1-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUB-1-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUB-1-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUB-1.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-2-1024x671.png\" alt=\"\" class=\"wp-image-741\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-2-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-2-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-2-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-2-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-2-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-2.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-3-1024x671.png\" alt=\"\" class=\"wp-image-742\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-3-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-3-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-3-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-3-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-3-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-3.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-4-1024x671.png\" alt=\"\" class=\"wp-image-743\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-4-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-4-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-4-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-4-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-4-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/MAGAMISTUBA-4.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-1-1024x671.png\" alt=\"\" class=\"wp-image-745\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-1-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-1-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-1-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-1-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-1-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-1.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-2-1024x671.png\" alt=\"\" class=\"wp-image-746\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-2-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-2-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-2-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-2-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-2-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-2.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-3-1024x671.png\" alt=\"\" class=\"wp-image-747\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-3-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-3-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-3-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-3-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-3-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-3.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-4-1024x671.png\" alt=\"\" class=\"wp-image-748\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-4-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-4-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-4-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-4-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-4-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/VANNITUBA-4.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1450\" height=\"950\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-1024x671.png\" alt=\"\" class=\"wp-image-750\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/1.png 1450w\" sizes=\"auto, (max-width: 1450px) 100vw, 1450px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-1024x671.png\" alt=\"\" class=\"wp-image-751\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/2.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/3-1024x671.png\" alt=\"\" class=\"wp-image-752\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/3-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/3-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/3-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/3-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/3-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/3.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/4-1024x671.png\" alt=\"\" class=\"wp-image-753\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/4-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/4-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/4-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/4-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/4-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/4.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/5-1024x671.png\" alt=\"\" class=\"wp-image-754\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/5-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/5-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/5-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/5-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/5-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/5.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/6-1024x671.png\" alt=\"\" class=\"wp-image-755\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/6-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/6-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/6-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/6-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/6-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/6.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/7-1024x671.png\" alt=\"\" class=\"wp-image-756\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/7-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/7-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/7-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/7-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/7-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/7.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/8-1024x671.png\" alt=\"\" class=\"wp-image-757\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/8-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/8-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/8-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/8-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/8-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/8.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-1-1024x671.png\" alt=\"\" class=\"wp-image-760\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-1-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-1-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-1-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-1-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-1-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-1.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-2-1024x671.png\" alt=\"\" class=\"wp-image-761\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-2-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-2-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-2-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-2-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-2-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-2.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-3-1024x671.png\" alt=\"\" class=\"wp-image-762\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-3-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-3-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-3-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-3-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-3-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-3.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-5-1024x671.png\" alt=\"\" class=\"wp-image-765\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-5-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-5-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-5-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-5-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-5-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-5.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-6-1024x671.png\" alt=\"\" class=\"wp-image-766\" style=\"border-top-left-radius:26px;border-top-right-radius:26px;border-bottom-left-radius:26px;border-bottom-right-radius:26px\" srcset=\"https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-6-1024x671.png 1024w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-6-300x197.png 300w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-6-768x503.png 768w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-6-18x12.png 18w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-6-600x393.png 600w, https:\/\/lendle.ee\/wp-content\/uploads\/2026\/07\/AED-6.png 1450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div><\/div><div class=\"cb-pagination swiper-pagination\"><\/div><div class=\"cb-button-prev swiper-button-prev\"><\/div><div class=\"cb-button-next swiper-button-next\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-cb0a7ccb wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-x-large-font-size wp-block-paragraph\"><strong>Lendle House<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>45 minutes from Tallinn, P\u00e4rnu, and Haapsalu.<\/strong><\/p>\n\n\n\n<p class=\"ext-animate--on wp-block-paragraph\" style=\"margin-top:1.5rem\">Lendle House is a place born from the heart\u2014from a quiet desire to create a space where time stands still and the soul finds its own rhythm.<\/p>\n\n\n\n<p class=\"ext-animate--on wp-block-paragraph\" style=\"margin-top:1.5rem\">At Lendle House, we create gatherings that stay with you long after they\u2019re over. Seminar days that let ideas take root and grow. Every visit to Lendle House is special, created in collaboration with you. It\u2019s a place to come to breathe, gather, and celebrate. A family vacation, a seminar, a birthday, or just a get-together. It\u2019s easy to be here.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>House amenities<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A fully equipped two-story house that offers maximum comfort for the whole group. The house has 4 bedrooms, 3 of which are on the ground floor and 1 on the second floor. It features a kitchen with a coffee maker, a spacious living room with a TV, and a bathroom with soft towels and toiletries. There\u2019s a large yard with a playground and a trampoline, as well as a terrace with comfortable furniture.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Additional services<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In collaboration with trusted partners, we can provide everything from simple snacks to a lavish banquet. We also offer seminar planning and recreational activities\u2014such as hikes, workshops, and photo sessions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Check-in and check-out times<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00b7<\/strong> Check-in starting at 3:00 p.m. or by arrangement<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00b7<\/strong> Check-out by 12:00 p.m. at the latest, or by arrangement<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons alignwide is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-foreground-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/lendle.ee\/en\/maja-broneerimine\/\" style=\"border-top-left-radius:51px;border-top-right-radius:51px;border-bottom-left-radius:51px;border-bottom-right-radius:51px;background-color:#b3d6f2\">Book<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-style-ext-preset--group--natural-1--footer-1 has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained is-style-ext-preset--group--natural-1--footer-1--5\" style=\"background-color:#eaeaff;padding-top:0;padding-bottom:0\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-cb0a7ccb wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u00a9 2026 Lendle Peace &amp;\u00a0Wellness\u00a0Stay O\u00dc. All rights reserved.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Lendle Maja 45 minuti kaugusel Tallinnast, P\u00e4rnust &amp; Haapsalust. Lendle Maja on koht, mis on s\u00fcndinud s\u00fcdamest &#8211; vaiksest soovist luua paik, kus aeg peatub ning hing leiab oma r\u00fctmi. Rahu elab hetkes, mille saad kinkida iseendale, perele, s\u00f5pradele. Lendle Majas s\u00fcnnivad koosviibimised, mis j\u00e4\u00e4vad hinge kauemaks. Seminarip\u00e4evad, mis lubavad ideedel kasvada. Iga k\u00fclastus Lendle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-with-title","meta":{"footnotes":""},"class_list":["post-247","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lendle Maja 45 minuti kaugusel Tallinnast, P\u00e4rnust &amp; Haapsalust. Lendle Maja on koht, mis on s\u00fcndinud s\u00fcdamest - vaiksest soovist luua paik, kus aeg peatub ning hing leiab oma r\u00fctmi. Rahu elab hetkes, mille saad kinkida iseendale, perele, s\u00f5pradele. Lendle Majas s\u00fcnnivad koosviibimised, mis j\u00e4\u00e4vad hinge kauemaks. Seminarip\u00e4evad, mis lubavad ideedel kasvada. Iga k\u00fclastus Lendle\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/lendle.ee\/en\/lendle-maja-tutvustus\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Lendle -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Majutuse \u00dclevaade - Lendle\" \/>\n\t\t<meta property=\"og:description\" content=\"Lendle Maja 45 minuti kaugusel Tallinnast, P\u00e4rnust &amp; Haapsalust. Lendle Maja on koht, mis on s\u00fcndinud s\u00fcdamest - vaiksest soovist luua paik, kus aeg peatub ning hing leiab oma r\u00fctmi. Rahu elab hetkes, mille saad kinkida iseendale, perele, s\u00f5pradele. Lendle Majas s\u00fcnnivad koosviibimised, mis j\u00e4\u00e4vad hinge kauemaks. Seminarip\u00e4evad, mis lubavad ideedel kasvada. Iga k\u00fclastus Lendle\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/lendle.ee\/en\/lendle-maja-tutvustus\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-03-19T17:00:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-15T07:18:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Majutuse \u00dclevaade - Lendle\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lendle Maja 45 minuti kaugusel Tallinnast, P\u00e4rnust &amp; Haapsalust. Lendle Maja on koht, mis on s\u00fcndinud s\u00fcdamest - vaiksest soovist luua paik, kus aeg peatub ning hing leiab oma r\u00fctmi. Rahu elab hetkes, mille saad kinkida iseendale, perele, s\u00f5pradele. Lendle Majas s\u00fcnnivad koosviibimised, mis j\u00e4\u00e4vad hinge kauemaks. Seminarip\u00e4evad, mis lubavad ideedel kasvada. Iga k\u00fclastus Lendle\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lendle.ee\\\/en\\\/lendle-maja-tutvustus\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lendle.ee\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lendle.ee\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lendle.ee\\\/en\\\/lendle-maja-tutvustus\\\/#listItem\",\"name\":\"Majutuse \\u00dclevaade\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lendle.ee\\\/en\\\/lendle-maja-tutvustus\\\/#listItem\",\"position\":2,\"name\":\"Majutuse \\u00dclevaade\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lendle.ee\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lendle.ee\\\/en\\\/#organization\",\"name\":\"Lendle\",\"url\":\"https:\\\/\\\/lendle.ee\\\/en\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lendle.ee\\\/en\\\/lendle-maja-tutvustus\\\/#webpage\",\"url\":\"https:\\\/\\\/lendle.ee\\\/en\\\/lendle-maja-tutvustus\\\/\",\"name\":\"Majutuse \\u00dclevaade - Lendle\",\"description\":\"Lendle Maja 45 minuti kaugusel Tallinnast, P\\u00e4rnust & Haapsalust. Lendle Maja on koht, mis on s\\u00fcndinud s\\u00fcdamest - vaiksest soovist luua paik, kus aeg peatub ning hing leiab oma r\\u00fctmi. Rahu elab hetkes, mille saad kinkida iseendale, perele, s\\u00f5pradele. Lendle Majas s\\u00fcnnivad koosviibimised, mis j\\u00e4\\u00e4vad hinge kauemaks. Seminarip\\u00e4evad, mis lubavad ideedel kasvada. Iga k\\u00fclastus Lendle\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lendle.ee\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lendle.ee\\\/en\\\/lendle-maja-tutvustus\\\/#breadcrumblist\"},\"datePublished\":\"2026-03-19T17:00:12+00:00\",\"dateModified\":\"2026-07-15T07:18:46+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lendle.ee\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lendle.ee\\\/en\\\/\",\"name\":\"Lendle\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/lendle.ee\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Majutuse \u00dclevaade - Lendle","description":"Lendle Maja 45 minuti kaugusel Tallinnast, P\u00e4rnust & Haapsalust. Lendle Maja on koht, mis on s\u00fcndinud s\u00fcdamest - vaiksest soovist luua paik, kus aeg peatub ning hing leiab oma r\u00fctmi. Rahu elab hetkes, mille saad kinkida iseendale, perele, s\u00f5pradele. Lendle Majas s\u00fcnnivad koosviibimised, mis j\u00e4\u00e4vad hinge kauemaks. Seminarip\u00e4evad, mis lubavad ideedel kasvada. Iga k\u00fclastus Lendle","canonical_url":"https:\/\/lendle.ee\/en\/lendle-maja-tutvustus\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/lendle.ee\/en\/lendle-maja-tutvustus\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/lendle.ee\/en#listItem","position":1,"name":"Home","item":"https:\/\/lendle.ee\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/lendle.ee\/en\/lendle-maja-tutvustus\/#listItem","name":"Majutuse \u00dclevaade"}},{"@type":"ListItem","@id":"https:\/\/lendle.ee\/en\/lendle-maja-tutvustus\/#listItem","position":2,"name":"Majutuse \u00dclevaade","previousItem":{"@type":"ListItem","@id":"https:\/\/lendle.ee\/en#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/lendle.ee\/en\/#organization","name":"Lendle","url":"https:\/\/lendle.ee\/en\/"},{"@type":"WebPage","@id":"https:\/\/lendle.ee\/en\/lendle-maja-tutvustus\/#webpage","url":"https:\/\/lendle.ee\/en\/lendle-maja-tutvustus\/","name":"Majutuse \u00dclevaade - Lendle","description":"Lendle Maja 45 minuti kaugusel Tallinnast, P\u00e4rnust & Haapsalust. Lendle Maja on koht, mis on s\u00fcndinud s\u00fcdamest - vaiksest soovist luua paik, kus aeg peatub ning hing leiab oma r\u00fctmi. Rahu elab hetkes, mille saad kinkida iseendale, perele, s\u00f5pradele. Lendle Majas s\u00fcnnivad koosviibimised, mis j\u00e4\u00e4vad hinge kauemaks. Seminarip\u00e4evad, mis lubavad ideedel kasvada. Iga k\u00fclastus Lendle","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/lendle.ee\/en\/#website"},"breadcrumb":{"@id":"https:\/\/lendle.ee\/en\/lendle-maja-tutvustus\/#breadcrumblist"},"datePublished":"2026-03-19T17:00:12+00:00","dateModified":"2026-07-15T07:18:46+00:00"},{"@type":"WebSite","@id":"https:\/\/lendle.ee\/en\/#website","url":"https:\/\/lendle.ee\/en\/","name":"Lendle","inLanguage":"en-US","publisher":{"@id":"https:\/\/lendle.ee\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Lendle -","og:type":"article","og:title":"Majutuse \u00dclevaade - Lendle","og:description":"Lendle Maja 45 minuti kaugusel Tallinnast, P\u00e4rnust &amp; Haapsalust. Lendle Maja on koht, mis on s\u00fcndinud s\u00fcdamest - vaiksest soovist luua paik, kus aeg peatub ning hing leiab oma r\u00fctmi. Rahu elab hetkes, mille saad kinkida iseendale, perele, s\u00f5pradele. Lendle Majas s\u00fcnnivad koosviibimised, mis j\u00e4\u00e4vad hinge kauemaks. Seminarip\u00e4evad, mis lubavad ideedel kasvada. Iga k\u00fclastus Lendle","og:url":"https:\/\/lendle.ee\/en\/lendle-maja-tutvustus\/","article:published_time":"2026-03-19T17:00:12+00:00","article:modified_time":"2026-07-15T07:18:46+00:00","twitter:card":"summary_large_image","twitter:title":"Majutuse \u00dclevaade - Lendle","twitter:description":"Lendle Maja 45 minuti kaugusel Tallinnast, P\u00e4rnust &amp; Haapsalust. Lendle Maja on koht, mis on s\u00fcndinud s\u00fcdamest - vaiksest soovist luua paik, kus aeg peatub ning hing leiab oma r\u00fctmi. Rahu elab hetkes, mille saad kinkida iseendale, perele, s\u00f5pradele. Lendle Majas s\u00fcnnivad koosviibimised, mis j\u00e4\u00e4vad hinge kauemaks. Seminarip\u00e4evad, mis lubavad ideedel kasvada. Iga k\u00fclastus Lendle"},"aioseo_meta_data":{"post_id":"247","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-03-19 17:00:13","updated":"2026-07-15 07:18:46","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lendle.ee\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMajutuse \u00dclevaade\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/lendle.ee\/en"},{"label":"Majutuse \u00dclevaade","link":"https:\/\/lendle.ee\/en\/lendle-maja-tutvustus\/"}],"_links":{"self":[{"href":"https:\/\/lendle.ee\/en\/wp-json\/wp\/v2\/pages\/247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lendle.ee\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lendle.ee\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lendle.ee\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lendle.ee\/en\/wp-json\/wp\/v2\/comments?post=247"}],"version-history":[{"count":17,"href":"https:\/\/lendle.ee\/en\/wp-json\/wp\/v2\/pages\/247\/revisions"}],"predecessor-version":[{"id":792,"href":"https:\/\/lendle.ee\/en\/wp-json\/wp\/v2\/pages\/247\/revisions\/792"}],"wp:attachment":[{"href":"https:\/\/lendle.ee\/en\/wp-json\/wp\/v2\/media?parent=247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}